{"id":9307,"date":"2014-06-05T10:53:24","date_gmt":"2014-06-05T13:53:24","guid":{"rendered":"https:\/\/www.cnpem.staging.wpengine.com\/?p=8073"},"modified":"2026-03-12T11:41:16","modified_gmt":"2026-03-12T14:41:16","slug":"centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas","status":"publish","type":"post","link":"https:\/\/cnpem.br\/en\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/","title":{"rendered":"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas"},"content":{"rendered":"<p><em>Portal do MCTI em 04\/06\/2014<\/em><\/p>\n<p style=\"text-align: justify;\">O Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), organiza\u00e7\u00e3o social qualificada pelo Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI), divulgou chamada para tr\u00eas modalidades de Bolsas Capes.<\/p>\n<p style=\"text-align: justify;\"><span style=\"font-size: 13px;\">Ser\u00e3o at\u00e9 cinco bolsas de pesquisador visitante do exterior, at\u00e9 dez de p\u00f3s-doutorado e uma de pesquisador visitante s\u00eanior. Os candidatos selecionados atuar\u00e3o em projetos desenvolvidos pelos laborat\u00f3rios que comp\u00f5em o centro: Laborat\u00f3rio Nacional de Luz S\u00edncrotron (LNLS), Laborat\u00f3rio Nacional de Bioci\u00eancias (LNBio), Laborat\u00f3rio Nacional de Ci\u00eancia e Tecnologia do Bioetanol (CTBE) e Laborat\u00f3rio Nacional de Nanotecnologia (LNNano).<\/span><\/p>\n<p style=\"text-align: justify;\">A sele\u00e7\u00e3o dos candidatos ser\u00e1 feita por um comit\u00ea formado por representantes do CNPEM e da Coordena\u00e7\u00e3o de Aperfei\u00e7oamento de Pessoal de N\u00edvel Superior (Capes).<\/p>\n<p style=\"text-align: justify;\">O processo de sele\u00e7\u00e3o permanecer\u00e1 aberto at\u00e9 que todas as vagas sejam preenchidas e o programa tem validade at\u00e9 dezembro de 2018. <a href=\"https:\/\/www.cnpem.staging.wpengine.com\/blog\/2014\/06\/04\/centro-nacional-de-pesquisa-em-energia-e-materiais-divulga-chamada-para-bolsas-em-parceria-com-a-capes\/\" target=\"_blank\" rel=\"noopener\">Saiba mais.<\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Repercuss\u00e3o: <\/strong><a href=\"https:\/\/www.brasil.gov.br\/ciencia-e-tecnologia\/2014\/06\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\" target=\"_blank\" rel=\"noopener\">Portal Brasil<\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Portal do MCTI em 04\/06\/2014 O Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), organiza\u00e7\u00e3o social qualificada pelo Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI), divulgou chamada para tr\u00eas&hellip;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1163,4],"tags":[],"class_list":["post-9307","post","type-post","status-publish","format-standard","hentry","category-clipping-cnpem","category-oportunidades","category-1163","category-4","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas - CNPEM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas - CNPEM\" \/>\n<meta property=\"og:description\" content=\"Portal do MCTI em 04\/06\/2014 O Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), organiza\u00e7\u00e3o social qualificada pelo Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI), divulgou chamada para tr\u00eas&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/\" \/>\n<meta property=\"og:site_name\" content=\"CNPEM\" \/>\n<meta property=\"article:published_time\" content=\"2014-06-05T13:53:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-12T14:41:16+00:00\" \/>\n<meta name=\"author\" content=\"Erik Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/\"},\"author\":{\"name\":\"Erik Medina\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"headline\":\"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas\",\"datePublished\":\"2014-06-05T13:53:24+00:00\",\"dateModified\":\"2026-03-12T14:41:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/\"},\"wordCount\":176,\"articleSection\":[\"CNPEM na M\u00eddia\",\"Oportunidades\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/\",\"url\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas - CNPEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\"},\"datePublished\":\"2014-06-05T13:53:24+00:00\",\"dateModified\":\"2026-03-12T14:41:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnpem.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\",\"url\":\"https:\\\/\\\/cnpem.br\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"description\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"alternateName\":\"CNPEM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnpem.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\",\"name\":\"Erik Medina\",\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas - CNPEM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/","og_locale":"en_US","og_type":"article","og_title":"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas - CNPEM","og_description":"Portal do MCTI em 04\/06\/2014 O Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), organiza\u00e7\u00e3o social qualificada pelo Minist\u00e9rio da Ci\u00eancia, Tecnologia e Inova\u00e7\u00e3o (MCTI), divulgou chamada para tr\u00eas&hellip;","og_url":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/","og_site_name":"CNPEM","article_published_time":"2014-06-05T13:53:24+00:00","article_modified_time":"2026-03-12T14:41:16+00:00","author":"Erik Medina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Erik Medina","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/#article","isPartOf":{"@id":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/"},"author":{"name":"Erik Medina","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"headline":"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas","datePublished":"2014-06-05T13:53:24+00:00","dateModified":"2026-03-12T14:41:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/"},"wordCount":176,"articleSection":["CNPEM na M\u00eddia","Oportunidades"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/","url":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/","name":"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas - CNPEM","isPartOf":{"@id":"https:\/\/cnpem.br\/#website"},"datePublished":"2014-06-05T13:53:24+00:00","dateModified":"2026-03-12T14:41:16+00:00","author":{"@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"breadcrumb":{"@id":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnpem.br\/centro-nacional-de-pesquisa-em-energia-e-materiais-oferece-bolsas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnpem.br\/en\/"},{"@type":"ListItem","position":2,"name":"Centro Nacional de Pesquisa em Energia e Materiais oferece bolsas"}]},{"@type":"WebSite","@id":"https:\/\/cnpem.br\/#website","url":"https:\/\/cnpem.br\/","name":"Centro Nacional de Pesquisa em Energia e Materiais","description":"Centro Nacional de Pesquisa em Energia e Materiais","alternateName":"CNPEM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnpem.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef","name":"Erik Medina","url":""}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/per0Mi-2q7","_links":{"self":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/9307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=9307"}],"version-history":[{"count":0,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/9307\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=9307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=9307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=9307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}