{"id":23517,"date":"2021-05-04T19:55:22","date_gmt":"2021-05-04T19:55:22","guid":{"rendered":"https:\/\/cnpem.staging.wpengine.com\/?p=23517"},"modified":"2026-03-02T15:54:42","modified_gmt":"2026-03-02T18:54:42","slug":"cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina","status":"publish","type":"post","link":"https:\/\/cnpem.br\/en\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/","title":{"rendered":"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina"},"content":{"rendered":"<p><a href=\"https:\/\/www1.folha.uol.com.br\/equilibrioesaude\/2021\/04\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina.shtml\">Folha de S\u00e3o Paulo<\/a> em 21\/04\/2021<\/p>\n<p>Pesquisadores que trabalham na\u00a0linha de frente\u00a0da investiga\u00e7\u00e3o da Covid-19, muito deles lidando com amostras de pacientes contaminados pelo v\u00edrus Sars-CoV-2 e cobaias infectadas, n\u00e3o foram inclu\u00eddos nos grupos priorit\u00e1rios para a vacina\u00e7\u00e3o.<\/p>\n<p>H\u00e1 um movimento em curso pedindo \u00e0s autoridades de sa\u00fade que incluam esses grupos nos planos de imuniza\u00e7\u00e3o. Muitos desses cientistas atuam no desenvolvimento de vacinas, medicamentos e testes diagn\u00f3sticos, al\u00e9m linhas de pesquisa para entender a din\u00e2mica da doen\u00e7a e suas sequelas.<\/p>\n<p>Os pesquisadores que conseguiram ser vacinados at\u00e9 agora o foram por meio de acordos locais, entre as universidades e os munic\u00edpios.<\/p>\n<p>Mas, na\u00a0falta de uma pol\u00edtica clara\u00a0que os coloque como priorit\u00e1rios, a maioria segue sem imuniza\u00e7\u00e3o. Um abaixo-assinado re\u00fane assinaturas de quase mil pesquisadores pelo pa\u00eds que enfrentam essa situa\u00e7\u00e3o.<\/p>\n<p>\u201cO ministro, os secret\u00e1rios da Sa\u00fade, o governador, todo mundo diz que segue a ci\u00eancia. Mas parece que quem faz a ci\u00eancia foi cancelado, n\u00e3o existe. Os cientistas s\u00e3o invis\u00edveis\u201d, diz o pesquisador Fernando de Queiroz Cunha, professor do departamento de farmacologia da USP Ribeir\u00e3o Preto.<\/p>\n<p>Ali, ao menos 80 pesquisadores est\u00e3o h\u00e1 mais de um ano trabalhando com o v\u00edrus e n\u00e3o foram vacinados.<\/p>\n<p>\u201cUma parte deles trabalha em ambiente NB-3, cujo risco de contamina\u00e7\u00e3o \u00e9 semelhante ou at\u00e9 superior ao de uma UTI Covid, porque trabalha com com amostras e camundongos infectados\u201d, diz Cunha.<\/p>\n<p>Ele justifica o risco superior ao fato de que, quando um paciente infectado est\u00e1 na UTI, ele est\u00e1 sedado, n\u00e3o faz \u201cestripulias\u201d.<\/p>\n<p>\u201cO camundongo pode brigar, te morder, pode acontecer uma contamina\u00e7\u00e3o grande. A gente usa duplas luvas, o ar que respiramos na sala NB-3 \u00e9 filtrado, mas, ainda assim, tem risco de contaminar. Essas pessoas trabalham de segunda a domingo, n\u00e3o tem hor\u00e1rio\u201d, explica.<\/p>\n<p>Cunha diz que os cientistas j\u00e1 recorreram a todas as inst\u00e2ncias da USP, da Prefeitura de Ribeir\u00e3o Preto e do governo paulista, mas o impasse continua.<\/p>\n<p>Em nota, a Secretaria Municipal de Sa\u00fade de Ribeir\u00e3o Preto diz que segue a orienta\u00e7\u00e3o do PNI (Programa Nacional de Imuniza\u00e7\u00f5es), que a distribui\u00e7\u00e3o e quantidade de doses s\u00e3o efetuadas pelo governo paulista e que os munic\u00edpios n\u00e3o t\u00eam autonomia para mudar as prioridades do estado.<\/p>\n<p>J\u00e1 a Secretaria de Estado da Sa\u00fade informa, tamb\u00e9m em nota, que aqueles que atuam em laborat\u00f3rios e os acad\u00eamicos em sa\u00fade est\u00e3o inclu\u00eddos nas subcategorias de trabalhadores da sa\u00fade.<\/p>\n<p>&#8220;As doses para todos os p\u00fablicos-alvo s\u00e3o enviadas aos munic\u00edpios para aplica\u00e7\u00e3o nas pessoas que o integram, sendo prerrogativa da prefeitura deflagrar as estrat\u00e9gias necess\u00e1rias para imunizar tais p\u00fablicos.&#8221;<\/p>\n<p>No laborat\u00f3rio de miocrobiota e imunomodula\u00e7\u00e3o coordenado pela professora Ang\u00e9lica Vieira, do departamento de bioqu\u00edmica e imunologia da UFMG (Universidade Federal de Minas Gerais), ningu\u00e9m ainda foi vacinado, apesar de os alunos irem at\u00e9 a casa de pacientes infectados para coletar amostras de sangue e de fezes.<\/p>\n<p>O foco da pesquisa \u00e9 tentar compreender as\u00a0sequelas de quem teve Covid-19, a partir da resposta inflamat\u00f3ria pulmonar, e buscar op\u00e7\u00f5es terap\u00eauticas para preveni-las.<\/p>\n<blockquote><p>\u201cEles n\u00e3o s\u00f3 v\u00e3o at\u00e9 as casas dos pacientes como depois manipulam essas amostras no laborat\u00f3rio. Mesmo com o exame PCR negativado, existe a hip\u00f3tese de o v\u00edrus ainda estar presente nas fezes, o que aumentaria muito o risco de infec\u00e7\u00e3o.\u201d<\/p><\/blockquote>\n<p>Recentemente, pela falta de seguran\u00e7a, a pesquisa foi freada. \u201cN\u00e3o quero prejudicar meus alunos. Muitos dependem do transporte p\u00fablico para se deslocar at\u00e9 a universidade, um risco vai se somando ao outro. A gente precisa encontrar uma forma de proteger esses jovens cientistas\u201d, diz que ela, que tamb\u00e9m ainda n\u00e3o foi imunizada.<\/p>\n<p>Para Marcelo Mori, que coordena a for\u00e7a-tarefa da Unicamp (Universidade Estadual de Campinas), de uma forma geral, os pesquisadores que trabalham na linha de frente com estudos sobre a Covid-19 acabaram sendo negligenciados na pol\u00edtica de vacina\u00e7\u00e3o.<\/p>\n<blockquote><p>\u201cA contribui\u00e7\u00e3o dos cientistas brasileiros para entendimento da Covid-19, tratamentos, novas variantes, tem sido muito grande, com muitas publica\u00e7\u00f5es internacionais relevantes. Para isso tudo acontecer, requer gente trabalhando, n\u00e3o s\u00f3 os professores, mas principalmente os alunos de p\u00f3s-gradua\u00e7\u00e3o.&#8221;<\/p><\/blockquote>\n<p>Ele lembra que em uma pol\u00edtica normal de laborat\u00f3rios de risco biol\u00f3gico elevado, as pessoas que ali trabalham precisam ser protegidas, inclusive vacinadas. \u201c\u00c9 uma condi\u00e7\u00e3o necess\u00e1ria para que essas pessoas continuem trabalhando.\u201d<\/p>\n<p>No caso da Unicamp, houve um entendimento com a institui\u00e7\u00e3o e os cientistas foram vacinados. \u201cMas como n\u00e3o existe uma pol\u00edtica p\u00fablica de vacina\u00e7\u00e3o para esse grupo, ele tem que brigar. Algumas institui\u00e7\u00f5es conseguem, outras n\u00e3o.\u201d<\/p>\n<p>O virologista Rafael Elias Marques, pesquisador do CNPEM (Centro Nacional de Pesquisa em Energia e Materiais), conta que, desde o in\u00edcio da pandemia, ele e os alunos frequentam um laborat\u00f3rio NB-3 e estiveram expostos aos estoques de v\u00edrus e \u00e0s amostras contaminadas.<\/p>\n<p>\u201cEu e alguns alunos que lidamos com amostras de pacientes infectadas, tivemos a felicidade de ter recebido a primeira dose [da vacina] porque estamos ligados \u00e0 for\u00e7a-tarefa da Unicamp.\u201d<\/p>\n<p>Por\u00e9m, Marques diz que colegas de outras regi\u00f5es do pa\u00eds continuam sem acesso \u00e0 vacina. \u201cCientistas que est\u00e3o processando amostras, fazendo diagn\u00f3sticos, trabalhando com modelos animais e in vitro, com pacientes, essas pessoas devem ser vacinadas com prioridade.\u201d<\/p>\n<p>Ele afirma que no ano passado houve um surto de Covid no laborat\u00f3rio onde atua e foi preciso fech\u00e1-lo e colocar 60 pessoas que atuam em pesquisas de testes diagn\u00f3sticos em quarentena.<\/p>\n<p>\u201c\u00c9 um risco que existia e que continua a existir. N\u00f3s, cientistas, estamos sofrendo press\u00e3o de v\u00e1rios setores da sociedade. Ou a nossa palavra n\u00e3o \u00e9 ouvida ou n\u00e3o temos os recursos adequados para fazer o trabalho que precisa se feito.&#8221;<\/p>\n<p>Para a qu\u00edmica Vanderlam Bolzani, presidente da Aciesp (Academia de Ci\u00eancias do Estado de S\u00e3o Paulo), \u00e9 um contrassenso das autoridades esse esquecimento daqueles que fazem a ci\u00eancia brasileira a andar. Ela diz que a Aciesp encaminhou of\u00edcio \u00e0 Secretaria de Estado da Sa\u00fade pedindo que os cientistas sejam colocados nas listas de prioridades de vacina\u00e7\u00e3o.<\/p>\n<p>Em nota, a Secretaria de Estado da Sa\u00fade diz que n\u00e3o foi localizada solicita\u00e7\u00e3o da Aciesp, mas que, de todo modo, tanto o Plano Nacional de Operacionaliza\u00e7\u00e3o da Vacina\u00e7\u00e3o contra Covid-19 definido pelo Minist\u00e9rio da Sa\u00fade quanto os documentos t\u00e9cnicos do Plano Estadual de Imuniza\u00e7\u00e3o de S\u00e3o Paulo deixam claras as subcategorias de trabalhadores de sa\u00fade, e os cientistas estariam inclu\u00eddos nelas.<\/p>\n<p>Procurado, o Minist\u00e9rio da Sa\u00fade n\u00e3o respondeu a raz\u00e3o pela qual os cientistas que atuam na linha de frente da pesquisa da Covid-19 n\u00e3o est\u00e3o sendo vacinados e o que pretende fazer sobre isso.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Folha de S\u00e3o Paulo em 21\/04\/2021 Pesquisadores que trabalham na\u00a0linha de frente\u00a0da investiga\u00e7\u00e3o da Covid-19, muito deles lidando com amostras de pacientes contaminados pelo v\u00edrus Sars-CoV-2 e cobaias infectadas, n\u00e3o&hellip;<\/p>\n","protected":false},"author":20,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1163,1208],"tags":[],"class_list":["post-23517","post","type-post","status-publish","format-standard","hentry","category-clipping-cnpem","category-releases-cnpem","category-1163","category-1208","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina - CNPEM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina - CNPEM\" \/>\n<meta property=\"og:description\" content=\"Folha de S\u00e3o Paulo em 21\/04\/2021 Pesquisadores que trabalham na\u00a0linha de frente\u00a0da investiga\u00e7\u00e3o da Covid-19, muito deles lidando com amostras de pacientes contaminados pelo v\u00edrus Sars-CoV-2 e cobaias infectadas, n\u00e3o&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/\" \/>\n<meta property=\"og:site_name\" content=\"CNPEM\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-04T19:55:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T18:54:42+00:00\" \/>\n<meta name=\"author\" content=\"Amanda Coltro\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Amanda Coltro\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/\"},\"author\":{\"name\":\"Amanda Coltro\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/11b85ad14c4b2950132dc4cd8769ceda\"},\"headline\":\"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina\",\"datePublished\":\"2021-05-04T19:55:22+00:00\",\"dateModified\":\"2026-03-02T18:54:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/\"},\"wordCount\":1214,\"articleSection\":[\"CNPEM na M\u00eddia\",\"Comunica\u00e7\u00e3o CNPEM\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/\",\"url\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/\",\"name\":\"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina - CNPEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\"},\"datePublished\":\"2021-05-04T19:55:22+00:00\",\"dateModified\":\"2026-03-02T18:54:42+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/11b85ad14c4b2950132dc4cd8769ceda\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnpem.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\",\"url\":\"https:\\\/\\\/cnpem.br\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"description\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"alternateName\":\"CNPEM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnpem.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/11b85ad14c4b2950132dc4cd8769ceda\",\"name\":\"Amanda Coltro\",\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina - CNPEM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/","og_locale":"en_US","og_type":"article","og_title":"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina - CNPEM","og_description":"Folha de S\u00e3o Paulo em 21\/04\/2021 Pesquisadores que trabalham na\u00a0linha de frente\u00a0da investiga\u00e7\u00e3o da Covid-19, muito deles lidando com amostras de pacientes contaminados pelo v\u00edrus Sars-CoV-2 e cobaias infectadas, n\u00e3o&hellip;","og_url":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/","og_site_name":"CNPEM","article_published_time":"2021-05-04T19:55:22+00:00","article_modified_time":"2026-03-02T18:54:42+00:00","author":"Amanda Coltro","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Amanda Coltro","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/#article","isPartOf":{"@id":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/"},"author":{"name":"Amanda Coltro","@id":"https:\/\/cnpem.br\/#\/schema\/person\/11b85ad14c4b2950132dc4cd8769ceda"},"headline":"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina","datePublished":"2021-05-04T19:55:22+00:00","dateModified":"2026-03-02T18:54:42+00:00","mainEntityOfPage":{"@id":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/"},"wordCount":1214,"articleSection":["CNPEM na M\u00eddia","Comunica\u00e7\u00e3o CNPEM"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/","url":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/","name":"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina - CNPEM","isPartOf":{"@id":"https:\/\/cnpem.br\/#website"},"datePublished":"2021-05-04T19:55:22+00:00","dateModified":"2026-03-02T18:54:42+00:00","author":{"@id":"https:\/\/cnpem.br\/#\/schema\/person\/11b85ad14c4b2950132dc4cd8769ceda"},"breadcrumb":{"@id":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnpem.br\/cientistas-que-pesquisam-covid-19-ficam-de-fora-dos-grupos-prioritarios-para-a-vacina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnpem.br\/en\/"},{"@type":"ListItem","position":2,"name":"Cientistas que pesquisam Covid-19 ficam de fora dos grupos priorit\u00e1rios para a vacina"}]},{"@type":"WebSite","@id":"https:\/\/cnpem.br\/#website","url":"https:\/\/cnpem.br\/","name":"Centro Nacional de Pesquisa em Energia e Materiais","description":"Centro Nacional de Pesquisa em Energia e Materiais","alternateName":"CNPEM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnpem.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cnpem.br\/#\/schema\/person\/11b85ad14c4b2950132dc4cd8769ceda","name":"Amanda Coltro","url":""}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/per0Mi-67j","_links":{"self":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/23517","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=23517"}],"version-history":[{"count":0,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/23517\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=23517"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=23517"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=23517"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}