{"id":23086,"date":"2020-12-03T15:10:38","date_gmt":"2020-12-03T15:10:38","guid":{"rendered":"https:\/\/cnpem.staging.wpengine.com\/?p=23086"},"modified":"2026-03-02T15:55:58","modified_gmt":"2026-03-02T18:55:58","slug":"espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes","status":"publish","type":"post","link":"https:\/\/cnpem.br\/en\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/","title":{"rendered":"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes"},"content":{"rendered":"<p><em>Assessoria de Comunica\u00e7\u00e3o em 03\/12\/2020<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>Composto inovador de nanofibras de celulose e l\u00e1tex de borracha natural desenvolvido no Centro Nacional de Pesquisas em Energia e Materiais (CNPEM) \u00e9 assunto de capa da revista<\/em> <a href=\"https:\/\/pubs.acs.org\/journal\/aanmf6?mobileUi=0&amp;\"><em>ACS Applied Nano Materials<\/em><\/a><em><u>.<\/u><\/em><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/pubs.acs.org\/journal\/aanmf6?mobileUi=0&amp;\" target=\"_blank\" rel=\"noopener noreferrer\"><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-23087\" src=\"https:\/\/i0.wp.com\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?resize=415%2C552&#038;ssl=1\" alt=\"\" width=\"415\" height=\"552\" srcset=\"https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?w=856&amp;ssl=1 856w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?resize=600%2C798&amp;ssl=1 600w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?resize=225%2C300&amp;ssl=1 225w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?resize=774%2C1030&amp;ssl=1 774w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?resize=768%2C1022&amp;ssl=1 768w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png?resize=530%2C705&amp;ssl=1 530w\" sizes=\"auto, (max-width: 415px) 100vw, 415px\" \/><\/a><\/p>\n<p>Pesquisadores do Centro Nacional de Pesquisa em Energia e Materiais (CNPEM) desenvolveram um processo 100% verde para produ\u00e7\u00e3o de um tipo de espuma que pode ser muito \u00fatil em tarefas de descontamina\u00e7\u00e3o de poluentes em \u00e1gua.<\/p>\n<p>O material, obtido a partir da combina\u00e7\u00e3o de fibrilas de nanocelulose e l\u00e1tex de borracha natural, demonstrou excelente capacidade de absor\u00e7\u00e3o de diversos tipos de \u00f3leos e solventes org\u00e2nicos. O artigo cient\u00edfico com detalhes dos experimentos ser\u00e1 assunto de capa da revista <a href=\"https:\/\/pubs.acs.org\/journal\/aanmf6?mobileUi=0&amp;\">ACS Applied <\/a><a href=\"https:\/\/pubs.acs.org\/journal\/aanmf6?mobileUi=0&amp;\">Nano Materials<\/a> do m\u00eas de novembro de 2020.<\/p>\n<p>O processo de produ\u00e7\u00e3o da espuma chama a aten\u00e7\u00e3o porque n\u00e3o usa nenhum produto derivado de petr\u00f3leo, somente materiais naturais abundantes na natureza e \u00e1gua como solvente.<\/p>\n<p>A pesquisadora Rubia Figueredo Gouveia, que coordena o estudo, explica que a nanocelulose sozinha n\u00e3o tem uma eficiente afinidade para absorver os poluentes analisados e ainda tem uma estrutura fr\u00e1gil, que se desfaz com muita facilidade em contato com \u00e1gua. \u201cA combina\u00e7\u00e3o com o l\u00e1tex de borracha natural \u00e9 que d\u00e1 a robustez necess\u00e1ria para a estrutura\u00e7\u00e3o 3D do material e a capacidade de absorver os poluentes\u201d.<\/p>\n<h2><strong>Efici\u00eancia patenteada<\/strong><\/h2>\n<p>A inova\u00e7\u00e3o, j\u00e1 com dep\u00f3sito de patente feito pelo <strong>CNPEM<\/strong>, tem diversas possibilidades de aplica\u00e7\u00e3o em filtros e processos de remedia\u00e7\u00e3o do meio ambiente, demonstrou ter alcan\u00e7ado caracter\u00edsticas ideais de porosidade e robustez da estrutura.\u00a0 Al\u00e9m do evidente diferencial no aproveitamento de biomassas renov\u00e1veis e abundantes na fabrica\u00e7\u00e3o, a espuma apresentou capacidade de absorver volumes de poluentes at\u00e9 50 vezes superiores \u00e0 sua massa, mesmo os mais viscosos. Testes tamb\u00e9m demonstraram que a espuma mant\u00e9m elevados n\u00edveis de efici\u00eancia de absor\u00e7\u00e3o mesmo ap\u00f3s 20 ciclos de reutiliza\u00e7\u00e3o, al\u00e9m da r\u00e1pida taxa de absor\u00e7\u00e3o, de 1s a 10s.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-23091\" src=\"https:\/\/i0.wp.com\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/Espuma_compLNNano.png?resize=486%2C371&#038;ssl=1\" alt=\"\" width=\"486\" height=\"371\" srcset=\"https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma_compLNNano.png?w=776&amp;ssl=1 776w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma_compLNNano.png?resize=600%2C457&amp;ssl=1 600w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma_compLNNano.png?resize=300%2C228&amp;ssl=1 300w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma_compLNNano.png?resize=768%2C585&amp;ssl=1 768w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma_compLNNano.png?resize=705%2C537&amp;ssl=1 705w\" sizes=\"auto, (max-width: 486px) 100vw, 486px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p><em><strong>Figura 1. Capacidade de absor\u00e7\u00e3o das espumas de nanocelulose e l\u00e1tex de borracha natural para diversos solventes org\u00e2nicos e \u00f3leos<\/strong><\/em><\/p>\n<h2><strong>O processo em microtomografias 3D<\/strong><\/h2>\n<p>O processo de obten\u00e7\u00e3o da espuma \u00e9 relativamente simples e r\u00e1pido. Os compostos s\u00f3lidos (nanocelulose e l\u00e1tex de borracha natural) representam apenas 2% da composi\u00e7\u00e3o da mistura dispersa em \u00e1gua. De acordo com a pesquisadora Rubia Figueredo Gouveia, esse percentual de 98% de \u00e1gua \u00e9 fundamental para a obten\u00e7\u00e3o da estrutura porosa da espuma, que se consolida ap\u00f3s etapas de congelamento e liofiliza\u00e7\u00e3o do composto.<\/p>\n<p>Imagens de microtomografia 3D e microscopia eletr\u00f4nica de varredura obtidas nos laborat\u00f3rios do <strong>CNPEM<\/strong> revelam os detalhes que fazem a diferen\u00e7a e demonstram as raz\u00f5es da efici\u00eancia na afinidade entre os materiais. \u201cAs fibrilas de nanocelulose se agrupam em uma estrutura 3D e, depois de recobertas e aderidas pelo l\u00e1tex, acabam se reorganizando em uma estrutura porosa mais robusta, que se interconectam e contribuem tanto para a robustez e estabilidade do material quanto para uma maior absor\u00e7\u00e3o dos poluentes\u201d, destaca a pesquisadora.<\/p>\n<p><img data-recalc-dims=\"1\" loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-23093 size-full\" src=\"https:\/\/i0.wp.com\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/Espuma-tomografia_lnnano.png?resize=382%2C280&#038;ssl=1\" alt=\"\" width=\"382\" height=\"280\" srcset=\"https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma-tomografia_lnnano.png?w=382&amp;ssl=1 382w, https:\/\/i0.wp.com\/cnpem.br\/wp-content\/uploads\/2020\/12\/Espuma-tomografia_lnnano.png?resize=300%2C220&amp;ssl=1 300w\" sizes=\"auto, (max-width: 382px) 100vw, 382px\" \/><\/p>\n<p style=\"text-align: center;\"><strong><em>Figura 2. Imagem 3D de microtomografia (esquerda) e microscopia eletr\u00f4nica de varredura (direita)<\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h4><strong>Sobre o CNPEM<\/strong><\/h4>\n<p>Ambiente de pesquisa e desenvolvimento sofisticado e efervescente, \u00fanico no Pa\u00eds e presente em poucos polos cient\u00edficos no mundo, o Centro Nacional de Pesquisa em Energia e Materiais (CNPEM) \u00e9 uma organiza\u00e7\u00e3o social supervisionada pelo Minist\u00e9rio da Ci\u00eancia, Tecnologia, Inova\u00e7\u00f5es (MCTI).<\/p>\n<p>O Centro \u00e9 constitu\u00eddo por quatro Laborat\u00f3rios Nacionais e \u00e9 ber\u00e7o do mais complexo projeto da ci\u00eancia brasileira \u2013 o Sirius \u2013 uma das mais avan\u00e7adas fontes de luz s\u00edncrotron do mundo.<\/p>\n<p>O CNPEM re\u00fane equipes multitem\u00e1ticas altamente especializadas, infraestruturas laboratoriais mundialmente competitivas e abertas \u00e0 comunidade cient\u00edfica, linhas de pesquisa em \u00e1reas estrat\u00e9gicas, projetos inovadores em parcerias com o setor produtivo e a\u00e7\u00f5es de treinamento para pesquisadores e estudantes.<\/p>\n<p>O Centro constitui um ambiente movido pela busca de solu\u00e7\u00f5es com impacto nas \u00e1reas de sa\u00fade, energia, meio ambiente, novos materiais, entre outras.<\/p>\n<p>As compet\u00eancias singulares e complementares presentes no CNPEM impulsionam pesquisas e desenvolvimentos nas \u00e1reas de luz s\u00edncrotron; engenharia de aceleradores; descoberta de novos medicamentos, inclusive a partir de esp\u00e9cies vegetais da biodiversidade brasileira; mecanismos moleculares envolvidos no surgimento e na progress\u00e3o do c\u00e2ncer, doen\u00e7as card\u00edacas e do neurodesenvolvimento; nanopart\u00edculas funcionalizadas para combate de bact\u00e9rias, v\u00edrus, c\u00e2ncer; novos sensores e dispositivos nanoestruturados para os setores de \u00f3leo e g\u00e1s e sa\u00fade; solu\u00e7\u00f5es biotecnol\u00f3gicas para o desenvolvimento sustent\u00e1vel de biocombust\u00edveis avan\u00e7ados, bioqu\u00edmicos e biomateriais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Assessoria de Comunica\u00e7\u00e3o em 03\/12\/2020 &nbsp; Composto inovador de nanofibras de celulose e l\u00e1tex de borracha natural desenvolvido no Centro Nacional de Pesquisas em Energia e Materiais (CNPEM) \u00e9 assunto&hellip;<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1208,962,1164],"tags":[],"class_list":["post-23086","post","type-post","status-publish","format-standard","hentry","category-releases-cnpem","category-releases-lnnano","category-noticia-home","category-1208","category-962","category-1164","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes - CNPEM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes - CNPEM\" \/>\n<meta property=\"og:description\" content=\"Assessoria de Comunica\u00e7\u00e3o em 03\/12\/2020 &nbsp; Composto inovador de nanofibras de celulose e l\u00e1tex de borracha natural desenvolvido no Centro Nacional de Pesquisas em Energia e Materiais (CNPEM) \u00e9 assunto&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/\" \/>\n<meta property=\"og:site_name\" content=\"CNPEM\" \/>\n<meta property=\"article:published_time\" content=\"2020-12-03T15:10:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T18:55:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png\" \/>\n<meta name=\"author\" content=\"Gustavo Moreno\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gustavo Moreno\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/\"},\"author\":{\"name\":\"Gustavo Moreno\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/142f9b4066e599dd651a3b9600c2c0ca\"},\"headline\":\"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes\",\"datePublished\":\"2020-12-03T15:10:38+00:00\",\"dateModified\":\"2026-03-02T18:55:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/\"},\"wordCount\":820,\"image\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnpem.staging.wpengine.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ACS_cover-espumaLNNano.png\",\"articleSection\":[\"Comunica\u00e7\u00e3o CNPEM\",\"Comunica\u00e7\u00e3o LNNano\",\"Not\u00edcia Home\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/\",\"url\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/\",\"name\":\"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes - CNPEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/cnpem.staging.wpengine.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ACS_cover-espumaLNNano.png\",\"datePublished\":\"2020-12-03T15:10:38+00:00\",\"dateModified\":\"2026-03-02T18:55:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/142f9b4066e599dd651a3b9600c2c0ca\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#primaryimage\",\"url\":\"https:\\\/\\\/cnpem.staging.wpengine.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ACS_cover-espumaLNNano.png\",\"contentUrl\":\"https:\\\/\\\/cnpem.staging.wpengine.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/ACS_cover-espumaLNNano.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnpem.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\",\"url\":\"https:\\\/\\\/cnpem.br\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"description\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"alternateName\":\"CNPEM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnpem.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/142f9b4066e599dd651a3b9600c2c0ca\",\"name\":\"Gustavo Moreno\",\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes - CNPEM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/","og_locale":"en_US","og_type":"article","og_title":"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes - CNPEM","og_description":"Assessoria de Comunica\u00e7\u00e3o em 03\/12\/2020 &nbsp; Composto inovador de nanofibras de celulose e l\u00e1tex de borracha natural desenvolvido no Centro Nacional de Pesquisas em Energia e Materiais (CNPEM) \u00e9 assunto&hellip;","og_url":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/","og_site_name":"CNPEM","article_published_time":"2020-12-03T15:10:38+00:00","article_modified_time":"2026-03-02T18:55:58+00:00","og_image":[{"url":"https:\/\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png","type":"","width":"","height":""}],"author":"Gustavo Moreno","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Gustavo Moreno","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#article","isPartOf":{"@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/"},"author":{"name":"Gustavo Moreno","@id":"https:\/\/cnpem.br\/#\/schema\/person\/142f9b4066e599dd651a3b9600c2c0ca"},"headline":"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes","datePublished":"2020-12-03T15:10:38+00:00","dateModified":"2026-03-02T18:55:58+00:00","mainEntityOfPage":{"@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/"},"wordCount":820,"image":{"@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#primaryimage"},"thumbnailUrl":"https:\/\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png","articleSection":["Comunica\u00e7\u00e3o CNPEM","Comunica\u00e7\u00e3o LNNano","Not\u00edcia Home"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/","url":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/","name":"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes - CNPEM","isPartOf":{"@id":"https:\/\/cnpem.br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#primaryimage"},"image":{"@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#primaryimage"},"thumbnailUrl":"https:\/\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png","datePublished":"2020-12-03T15:10:38+00:00","dateModified":"2026-03-02T18:55:58+00:00","author":{"@id":"https:\/\/cnpem.br\/#\/schema\/person\/142f9b4066e599dd651a3b9600c2c0ca"},"breadcrumb":{"@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#primaryimage","url":"https:\/\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png","contentUrl":"https:\/\/cnpem.staging.wpengine.com\/wp-content\/uploads\/2020\/12\/ACS_cover-espumaLNNano.png"},{"@type":"BreadcrumbList","@id":"https:\/\/cnpem.br\/espuma-feita-a-partir-de-materiais-naturais-mostra-eficiencia-na-absorcao-de-oleos-e-solventes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnpem.br\/en\/"},{"@type":"ListItem","position":2,"name":"Espuma feita a partir de materiais naturais mostra efici\u00eancia na absor\u00e7\u00e3o de \u00f3leos e solventes"}]},{"@type":"WebSite","@id":"https:\/\/cnpem.br\/#website","url":"https:\/\/cnpem.br\/","name":"Centro Nacional de Pesquisa em Energia e Materiais","description":"Centro Nacional de Pesquisa em Energia e Materiais","alternateName":"CNPEM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnpem.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cnpem.br\/#\/schema\/person\/142f9b4066e599dd651a3b9600c2c0ca","name":"Gustavo Moreno","url":""}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/per0Mi-60m","_links":{"self":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/23086","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=23086"}],"version-history":[{"count":0,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/23086\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=23086"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=23086"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=23086"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}