{"id":2061,"date":"2010-04-09T19:03:06","date_gmt":"2010-04-09T19:03:06","guid":{"rendered":"https:\/\/www.cnpem.staging.wpengine.com\/?p=2061"},"modified":"2026-03-03T10:20:02","modified_gmt":"2026-03-03T13:20:02","slug":"honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite","status":"publish","type":"post","link":"https:\/\/cnpem.br\/en\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/","title":{"rendered":"Honni soit qui mal y pense&#8221;, artigo de Rog\u00e9rio Cezar de Cerqueira Leite"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>09\/04\/2010 &#8211; Folha de S.Paulo<\/em><\/p>\n<p style=\"text-align: justify;\">Os benef\u00edcios da tecnologia de segunda gera\u00e7\u00e3o ficar\u00e3o \u00f3bvios quando, em breve, a falta de terras cultiv\u00e1veis vier a limitar a produ\u00e7\u00e3o<br \/>\nA prestigiosa revista &#8220;Science&#8221; publicou extensa reportagem sobre as origens e a cria\u00e7\u00e3o do Laborat\u00f3rio Nacional de Ci\u00eancia e Tecnologia do Bioetanol (CTBE, parte integrante do Centro Nacional de Pesquisas em Energia e Materiais), em que j\u00e1 foram investidos R$ 69 milh\u00f5es e outros tantos ser\u00e3o ainda necess\u00e1rios para sua implanta\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Essa iniciativa foi chamada na mesma reportagem de megaloman\u00edaca. Recentemente, os Estados Unidos dedicaram a projeto an\u00e1logo, aplicado em tr\u00eas centros universit\u00e1rios, US$ 1 bilh\u00e3o, ou seja, 12 vezes mais do que o investimento do CTBE.<\/p>\n<p style=\"text-align: justify;\">Se comparados aos respectivos PIBs, fica clara a pertin\u00eancia do programa brasileiro. Tamb\u00e9m o governo do Estado de S\u00e3o Paulo est\u00e1 investindo R$ 150 milh\u00f5es em biocombust\u00edveis nas tr\u00eas universidades paulistas.E ningu\u00e9m reclama. Talvez porque espere cada um receber sua quirera, embora, como sempre que h\u00e1 pulveriza\u00e7\u00e3o de recursos, os resultados esperados venham a ser p\u00edfios.<\/p>\n<p style=\"text-align: justify;\">Esperemos apenas que, sabedores que s\u00e3o dessa inexor\u00e1vel condi\u00e7\u00e3o, optem os respons\u00e1veis por uma distribui\u00e7\u00e3o que concentre recursos em poucos projetos. Esquecem ainda os cr\u00edticos extempor\u00e2neos que o CTBE \u00e9 um laborat\u00f3rio nacional, a cujos equipamentos e &#8220;expertises&#8221;, portanto, ter\u00e3o pleno acesso pesquisadores brasileiros e ind\u00fastrias nacionais.<\/p>\n<p style=\"text-align: justify;\">\u00c9 bom lembrar que os cinco programas de pesquisa e desenvolvimento do CTBE foram elaborados em estrita colabora\u00e7\u00e3o com \u00f3rg\u00e3os governamentais, universidades e empresas privadas e estatais, mais de 40 institui\u00e7\u00f5es ao todo, em um processo que durou cerca de dois anos.<\/p>\n<p style=\"text-align: justify;\">O professor Jos\u00e9 Goldemberg lembra com raz\u00e3o que ainda h\u00e1 muito a fazer pela melhoria da tecnologia de primeira gera\u00e7\u00e3o, implicando, todavia, que seriam prematuras iniciativas relativas \u00e0 tecnologia de segunda gera\u00e7\u00e3o. Eu esperaria essa argumenta\u00e7\u00e3o de um usineiro tradicional, nunca de um f\u00edsico.<\/p>\n<p style=\"text-align: justify;\">Que esse meu coment\u00e1rio n\u00e3o seja tomado como uma cr\u00edtica \u00e0 posi\u00e7\u00e3o do professor Goldemberg, mas apenas como uma sincera express\u00e3o de minha perplexidade. Explico-me: a cana-de-a\u00e7\u00facar, grosso modo, \u00e9 composta de \u00e1gua (50%), e o restante divide-se em um ter\u00e7o de suco (a\u00e7\u00facar), um ter\u00e7o de baga\u00e7o e um ter\u00e7o de palha. Ou seja, da biomassa total, apenas um ter\u00e7o \u00e9 aproveitado como a\u00e7\u00facar ou como \u00e1lcool; dois ter\u00e7os, o material lignocelul\u00f3sico, n\u00e3o s\u00e3o convertidos em a\u00e7\u00facar ou em \u00e1lcool dentro dos limites das tecnologias de primeira gera\u00e7\u00e3o.<\/p>\n<p style=\"text-align: justify;\">Uma parte dessa biomassa \u00e9 aproveitada, n\u00e3o obstante, frequentemente com efici\u00eancia muito baixa, para produzir a energia de que precisa a usina e, eventualmente, excedentes comercializ\u00e1veis.As tecnologias de segunda gera\u00e7\u00e3o permitir\u00e3o n\u00e3o somente total aproveitamento da biomassa contida na cana como tamb\u00e9m dos atuais rejeitos e sobras hoje inaproveitados de todas as demais culturas agr\u00edcolas.<\/p>\n<p style=\"text-align: justify;\">Os benef\u00edcios da tecnologia de segunda gera\u00e7\u00e3o se tornar\u00e3o \u00f3bvios quando, em futuro pr\u00f3ximo, a disponibilidade de terras cultiv\u00e1veis vier a limitar severamente a produ\u00e7\u00e3o. A produtividade por hectare pode em princ\u00edpio dobrar com a aplica\u00e7\u00e3o dessa tecnologia, mesmo que continuem as atuais formas de aproveitamento do baga\u00e7o e da palha.<\/p>\n<p style=\"text-align: justify;\">\u00c9 claro que pesquisas relativas \u00e0s tecnologias tradicionais devem continuar a ser realizadas, e o CTBE tamb\u00e9m a elas se dedica, mas o que alguns n\u00e3o percebem \u00e9 que estes dois poss\u00edveis ganhos, os pequenos incrementos progressivos em tecnologia de primeira gera\u00e7\u00e3o e o salto de produtividade devido \u00e0 introdu\u00e7\u00e3o de tecnologias de segunda gera\u00e7\u00e3o, n\u00e3o s\u00e3o mutuamente exclusivos, mas complementares, aditivos.<\/p>\n<p style=\"text-align: justify;\">Quanto ao diagn\u00f3stico de megalomania atribu\u00eddo aos idealizadores do CTBE, esse \u00e9 um fen\u00f4meno recorrente. Aconteceu quando foi criado o Instituto de F\u00edsica Gleb Wataghin, da Unicamp, ocorreu logo depois com o projeto do Laborat\u00f3rio Nacional de Luz S\u00edncrotron, ocorreu ainda com a Coppe, no Rio, em seu in\u00edcio etc.<\/p>\n<p style=\"text-align: justify;\">E o mais interessante \u00e9 que esses c\u00e9ticos, esses cr\u00edticos, n\u00e3o se incomodam com o eventual fracasso e consequente desperd\u00edcio de recursos, mas, muito pelo contr\u00e1rio, o que anima a sua f\u00faria verborr\u00e1gica \u00e9 a amea\u00e7a de sucesso do empreendimento.<\/p>\n<p style=\"text-align: justify;\">O surrado coment\u00e1rio que foi atribu\u00eddo a Beethoven, &#8220;Os c\u00e3es ladram e a caravana passa&#8221;, encontra uma vers\u00e3o mais apropriada no dizer de Sarmiento, o ex-presidente e intelectual argentino: &#8220;Os c\u00e3es ladram, \u00e9 sinal que cavalgamos&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>09\/04\/2010 &#8211; Folha de S.Paulo Os benef\u00edcios da tecnologia de segunda gera\u00e7\u00e3o ficar\u00e3o \u00f3bvios quando, em breve, a falta de terras cultiv\u00e1veis vier a limitar a produ\u00e7\u00e3o A prestigiosa revista&hellip;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1163,1224,12],"tags":[374,40,645,377],"class_list":["post-2061","post","type-post","status-publish","format-standard","hentry","category-clipping-cnpem","category-clipping-lnbr","category-clipping-lnls","tag-artigo","tag-cnpem","tag-honni-soit-qui-mal-y-pense","tag-rogerio-cezar-de-cerqueira-leite","category-1163","category-1224","category-12","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Honni soit qui mal y pense&quot;, artigo de Rog\u00e9rio Cezar de Cerqueira Leite - CNPEM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Honni soit qui mal y pense&quot;, artigo de Rog\u00e9rio Cezar de Cerqueira Leite - CNPEM\" \/>\n<meta property=\"og:description\" content=\"09\/04\/2010 &#8211; Folha de S.Paulo Os benef\u00edcios da tecnologia de segunda gera\u00e7\u00e3o ficar\u00e3o \u00f3bvios quando, em breve, a falta de terras cultiv\u00e1veis vier a limitar a produ\u00e7\u00e3o A prestigiosa revista&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/\" \/>\n<meta property=\"og:site_name\" content=\"CNPEM\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-09T19:03:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-03T13:20:02+00:00\" \/>\n<meta name=\"author\" content=\"Erik Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/\"},\"author\":{\"name\":\"Erik Medina\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"headline\":\"Honni soit qui mal y pense&#8221;, artigo de Rog\u00e9rio Cezar de Cerqueira Leite\",\"datePublished\":\"2010-04-09T19:03:06+00:00\",\"dateModified\":\"2026-03-03T13:20:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/\"},\"wordCount\":790,\"keywords\":[\"artigo\",\"CNPEM\",\"Honni soit qui mal y pense\\\"\",\"Rog\u00e9rio Cezar de Cerqueira Leite\"],\"articleSection\":[\"CNPEM na M\u00eddia\",\"LNBR na M\u00eddia\",\"LNLS na M\u00eddia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/\",\"url\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/\",\"name\":\"Honni soit qui mal y pense\\\", artigo de Rog\u00e9rio Cezar de Cerqueira Leite - CNPEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\"},\"datePublished\":\"2010-04-09T19:03:06+00:00\",\"dateModified\":\"2026-03-03T13:20:02+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnpem.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Honni soit qui mal y pense\\\", artigo de Rog\u00e9rio Cezar de Cerqueira Leite\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\",\"url\":\"https:\\\/\\\/cnpem.br\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"description\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"alternateName\":\"CNPEM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnpem.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\",\"name\":\"Erik Medina\",\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Honni soit qui mal y pense\", artigo de Rog\u00e9rio Cezar de Cerqueira Leite - CNPEM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/","og_locale":"en_US","og_type":"article","og_title":"Honni soit qui mal y pense\", artigo de Rog\u00e9rio Cezar de Cerqueira Leite - CNPEM","og_description":"09\/04\/2010 &#8211; Folha de S.Paulo Os benef\u00edcios da tecnologia de segunda gera\u00e7\u00e3o ficar\u00e3o \u00f3bvios quando, em breve, a falta de terras cultiv\u00e1veis vier a limitar a produ\u00e7\u00e3o A prestigiosa revista&hellip;","og_url":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/","og_site_name":"CNPEM","article_published_time":"2010-04-09T19:03:06+00:00","article_modified_time":"2026-03-03T13:20:02+00:00","author":"Erik Medina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Erik Medina","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/#article","isPartOf":{"@id":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/"},"author":{"name":"Erik Medina","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"headline":"Honni soit qui mal y pense&#8221;, artigo de Rog\u00e9rio Cezar de Cerqueira Leite","datePublished":"2010-04-09T19:03:06+00:00","dateModified":"2026-03-03T13:20:02+00:00","mainEntityOfPage":{"@id":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/"},"wordCount":790,"keywords":["artigo","CNPEM","Honni soit qui mal y pense\"","Rog\u00e9rio Cezar de Cerqueira Leite"],"articleSection":["CNPEM na M\u00eddia","LNBR na M\u00eddia","LNLS na M\u00eddia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/","url":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/","name":"Honni soit qui mal y pense\", artigo de Rog\u00e9rio Cezar de Cerqueira Leite - CNPEM","isPartOf":{"@id":"https:\/\/cnpem.br\/#website"},"datePublished":"2010-04-09T19:03:06+00:00","dateModified":"2026-03-03T13:20:02+00:00","author":{"@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"breadcrumb":{"@id":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnpem.br\/honni-soit-qui-mal-y-pense-artigo-de-rogerio-cezar-de-cerqueira-leite\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnpem.br\/en\/"},{"@type":"ListItem","position":2,"name":"Honni soit qui mal y pense\", artigo de Rog\u00e9rio Cezar de Cerqueira Leite"}]},{"@type":"WebSite","@id":"https:\/\/cnpem.br\/#website","url":"https:\/\/cnpem.br\/","name":"Centro Nacional de Pesquisa em Energia e Materiais","description":"Centro Nacional de Pesquisa em Energia e Materiais","alternateName":"CNPEM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnpem.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef","name":"Erik Medina","url":""}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/per0Mi-xf","_links":{"self":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/2061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=2061"}],"version-history":[{"count":0,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/2061\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=2061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=2061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=2061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}