{"id":16763,"date":"2017-05-26T18:51:52","date_gmt":"2017-05-26T18:51:52","guid":{"rendered":"https:\/\/cnpem.staging.wpengine.com\/?p=16763\/"},"modified":"2022-01-21T15:45:00","modified_gmt":"2022-01-21T18:45:00","slug":"em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos","status":"publish","type":"post","link":"https:\/\/cnpem.br\/en\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/","title":{"rendered":"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos"},"content":{"rendered":"<p><em><a href=\"https:\/\/jcnoticias.jornaldaciencia.org.br\/2-em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/\" target=\"_blank\" rel=\"noopener noreferrer\">JCNot\u00edcias<\/a>, 19\/05\/2017<\/em><\/p>\n<p>&nbsp;<\/p>\n<p><em>MCTIC sinaliza que projeto \u00e9 prioridade nos investimentos do PAC e prev\u00ea liberar R$ 189 milh\u00f5es entre maio e junho<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Em meio \u00e0 crise or\u00e7ament\u00e1ria que assola a ci\u00eancia, o andamento da obra civil do mega laborat\u00f3rio Sirius, em Campinas (SP) \u2013 projeto que deve elevar o patamar da ci\u00eancia brasileira no mundo \u2013 precisa da libera\u00e7\u00e3o imediata de R$ 66 milh\u00f5es, para dar sequ\u00eancia a etapas da constru\u00e7\u00e3o da infraestrutura prevista para ser inaugurada em junho de 2018, disse o cientista Ant\u00f4nio Jos\u00e9 Roque da Silva, respons\u00e1vel pelo projeto, ao\u00a0<em>Jornal da Ci\u00eancia<\/em>.<\/p>\n<p>Roque, como \u00e9 conhecido, esclarece que o cronograma de atividades do Sirius est\u00e1 em dia, mas que, para mant\u00ea-lo, ser\u00e1 necess\u00e1ria a r\u00e1pida libera\u00e7\u00e3o de novos recursos para fazer frente ao andamento da obra civil, a ser conclu\u00edda ainda este ano. Segundo ele, n\u00e3o existe mais margem para reorganiza\u00e7\u00e3o de atividades.<\/p>\n<p>O Projeto Sirius \u00e9 erguido pelo Laborat\u00f3rio Nacional de Luz S\u00edncrotron (LNLS), do qual o cientista \u00e9 diretor, e que faz parte do Centro Nacional de Pesquisa em Energia e Materiais (CNPEM).<\/p>\n<p>A iniciativa \u00e9 uma das prioridades dos parcos recursos do Programa de Acelera\u00e7\u00e3o do Crescimento (PAC), vinculado ao Minist\u00e9rio da Ci\u00eancia, Tecnologia, Inova\u00e7\u00f5es e Comunica\u00e7\u00f5es (MCTIC). Em mar\u00e7o, o governo federal bloqueou 42% do or\u00e7amento do PAC e o limitou em R$ 447 milh\u00f5es, na esteira do ajuste fiscal que contingenciou 44% do or\u00e7amento total da pasta. Em resposta a este jornal, o Minist\u00e9rio refor\u00e7a que, at\u00e9 agora, o cronograma do Projeto \u201cest\u00e1 rigorosamente em dia e que tem empenhado todos os esfor\u00e7os em prol da manuten\u00e7\u00e3o da programa\u00e7\u00e3o do Sirius.\u201d<\/p>\n<p>O Minist\u00e9rio, por interm\u00e9dio da assessoria de imprensa, confirma que n\u00e3o foi repassado nenhum recurso ao projeto este ano. Acrescenta, por\u00e9m, que a previs\u00e3o \u00e9 de liberar R$ 189 milh\u00f5es entre maio e junho. Al\u00e9m disso, mais R$ 136 milh\u00f5es devem ser repassados at\u00e9 o fim do ano, para dar continuidade ao projeto. Os dois repasses somam os R$ 325 milh\u00f5es que j\u00e1 constam da Lei Or\u00e7ament\u00e1ria Anual (R$ 325.933.705) aprovada para este ano.<\/p>\n<p>Divididas em tr\u00eas frentes \u2013 obras civis, aceleradores e esta\u00e7\u00f5es experimentais \u2013, as \u00e1reas do Sirius precisam caminhar juntas na velocidade apropriada para que o projeto final seja bem-sucedido, acrescentou o cientista.<\/p>\n<p>A primeira etapa de inaugura\u00e7\u00e3o, prevista para o pr\u00f3ximo ano, inclui a conclus\u00e3o da constru\u00e7\u00e3o do pr\u00e9dio principal da Fonte de Luz S\u00edncrotron de 4\u00aa gera\u00e7\u00e3o e de seus aceleradores, o que permitir\u00e1 a primeira volta dos el\u00e9trons no Sirius.<\/p>\n<p>\u201cEm 2018 entregaremos a obra civil, os aceleradores e quatro das 13 linhas de luz. A inaugura\u00e7\u00e3o do pr\u00f3ximo ano \u00e9 fundamental porque ser\u00e1 o in\u00edcio da luz s\u00edncrotron saindo do acelerador\u201d, refor\u00e7ou.<\/p>\n<p>A primeira parcela de recursos este ano deveria ter sido liberada em abril, isso n\u00e3o aconteceu em raz\u00e3o dos tr\u00e2mites normais de elabora\u00e7\u00e3o contratual, avalia Roque. Mesmo assim, a expectativa \u00e9 de que esses valores sejam repassados nos pr\u00f3ximos dias, uma vez que o termo aditivo anual foi assinado nos \u00faltimos dias pelas duas partes. Em 2016, esse carimbo foi concretizado em agosto; e o primeiro e \u00fanico repasse aconteceu somente em dezembro, na ordem R$ 182 milh\u00f5es, provenientes do bolo dos recursos repatriados.<\/p>\n<p><strong>Valores adicionais<\/strong><\/p>\n<p>Al\u00e9m da urg\u00eancia da parcela de R$ 66 milh\u00f5es, novos repasses s\u00e3o igualmente importantes no decorrer deste ano. No total, Roque calcula a necessidade de um or\u00e7amento de R$ 605 milh\u00f5es para garantir a inaugura\u00e7\u00e3o do Sirius em junho de 2018. Na ponta do l\u00e1pis, R$ 325 milh\u00f5es desse total j\u00e1 est\u00e3o assegurados pela LOA. J\u00e1 o restante de R$ 280 milh\u00f5es foi solicitado como suplementa\u00e7\u00e3o or\u00e7ament\u00e1ria ao MCTIC e ao Minist\u00e9rio do Planejamento.<\/p>\n<p>\u201cOs dois minist\u00e9rios est\u00e3o extremamente empenhados em buscar maneiras de viabilizar as necessidades do projeto para garantir o cronograma de inaugura\u00e7\u00e3o em junho de 2018\u201d, observa o cientista.<\/p>\n<p>Planejado desde 2012 e com a pedra fundamental lan\u00e7ada em 2014, o projeto Sirius \u00e9 or\u00e7ado em R$ 1,8 bilh\u00e3o at\u00e9 2020, quando deve estar 100% conclu\u00eddo. At\u00e9 o ano passado, o projeto recebeu investimentos de R$ 612 milh\u00f5es, o equivalente a um ter\u00e7o de todo o montante previsto.<\/p>\n<p>Conforme Roque, ainda \u201c\u00e9 cedo\u201d para avaliar eventuais impactos da crise or\u00e7ament\u00e1ria sobre o andamento das obras. Para ele, tudo depender\u00e1 de como ser\u00e3o as libera\u00e7\u00f5es de recursos e da manuten\u00e7\u00e3o do cronograma estabelecido inicialmente.<\/p>\n<p><strong>Benef\u00edcios ao Pa\u00eds<\/strong><\/p>\n<p>A proposta do Sirius, uma das m\u00e1quinas de luz s\u00edncrotron mais avan\u00e7adas do mundo, \u00e9 abrir novas perspectivas para pesquisas cient\u00edficas em todas as \u00e1reas do conhecimento, possivelmente a partir de 2019, quando o laborat\u00f3rio ser\u00e1 aberto para pesquisadores.<\/p>\n<p>\u201cEssa \u00e9 uma ferramenta que permitir\u00e1 qualquer \u00e1rea do conhecimento responder perguntas que hoje n\u00e3o podem ser respondidas no Brasil\u201d, disse Roque.<\/p>\n<p>Na pr\u00e1tica, s\u00edncrotron s\u00e3o grandes microsc\u00f3pios pelos quais ser\u00e3o realizados experimentos usando t\u00e9cnicas como nanotomografia e tomografia que permitem, por exemplo, investigar e fazer imagens de solo para identificar os motivos da coes\u00e3o do solo de Tabuleiros Costeiros, no Nordeste. Com extens\u00e3o de terra igual ou maior \u00e0 do Estado de S\u00e3o Paulo, a regi\u00e3o tem potencial agr\u00edcola, mas o cultivo de culturas como a cana-de-a\u00e7\u00facar possui baixa produtividade.<\/p>\n<p>\u201cO s\u00edncrotron \u00e9 uma ferramenta para auxiliar os pesquisadores a entender o porqu\u00ea dessa coes\u00e3o. Esse efeito, uma vez entendido, poder\u00e1 ser mitigado e ser\u00e1 poss\u00edvel aumentar a produtividade consideravelmente dessas regi\u00f5es\u201d, exemplificou o cientista.<\/p>\n<p>A iniciativa foi inclu\u00edda no PAC no ano passado a fim de assegurar os investimentos at\u00e9 o fim da obra. Assim, concorre com outros seis projetos dentro do PAC da pasta. S\u00e3o quatro da \u00e1rea de Comunica\u00e7\u00f5es; e tr\u00eas da fun\u00e7\u00e3o CT&amp;I que, al\u00e9m do Sirius, envolve o Reator Multiprop\u00f3sito Brasileiro (RMB) que prev\u00ea dar autonomia ao Brasil na produ\u00e7\u00e3o de radiof\u00e1rmacos usados no diagn\u00f3stico e no tratamento do c\u00e2ncer, por exemplo.<\/p>\n<p><strong>Cobertor curto da ci\u00eancia<\/strong><\/p>\n<p>Ao mesmo tempo em corre que para produzir uma das m\u00e1quinas mais avan\u00e7adas de luz s\u00edncrotron do mundo, a ci\u00eancia brasileira registra o pior or\u00e7amento da \u00faltima d\u00e9cada, limitado aos atuais R$ 3,25 bilh\u00f5es. E \u00e9 com esse cen\u00e1rio que a \u00e1rea \u00e9 inclu\u00edda na PEC do teto dos gastos p\u00fablicos que congela o or\u00e7amento federal por at\u00e9 duas d\u00e9cadas.<\/p>\n<p>Segundo Roque, os recursos da ci\u00eancia e tecnologia precisam crescer independentemente da necessidade de recursos adicionais para a manuten\u00e7\u00e3o do Projeto Sirius, considerando duas quest\u00f5es.<\/p>\n<p>\u201cPrimeira, os recursos de ci\u00eancia e tecnologia est\u00e3o em um patamar incompat\u00edvel com um pa\u00eds de tamanha magnitude, inadequados para as necessidades brasileiras e com o tamanho da comunidade cient\u00edfica que foi formada, sem falar na manuten\u00e7\u00e3o de todo o trabalho dessa comunidade\u201d, disse.<\/p>\n<p>\u201cSegunda, a constru\u00e7\u00e3o do Sirius \u00e9 importante para comunidade cient\u00edfica de forma ampla. O Sirius atua em todas as \u00e1reas do conhecimento e \u00e9 um projeto estruturante para a na\u00e7\u00e3o\u201d, disse o cientista que ainda n\u00e3o tem em m\u00e3os os c\u00e1lculos de or\u00e7amento que a manuten\u00e7\u00e3o da m\u00e1quina exigir\u00e1 por ano. Para Roque, \u00e9 fundamental estruturar uma pol\u00edtica mais ampla para que sejam otimizados todos os projetos brasileiros.<\/p>\n<p><em>Viviane Monteiro \u2013 Jornal da Ci\u00eancia<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Repercuss\u00e3o:\u00a0<a href=\"https:\/\/www.sintpq.org.br\/index.php\/blog\/item\/5148-em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\" target=\"_blank\" rel=\"noopener noreferrer\">SINTPq<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JCNot\u00edcias, 19\/05\/2017 &nbsp; MCTIC sinaliza que projeto \u00e9 prioridade nos investimentos do PAC e prev\u00ea liberar R$ 189 milh\u00f5es entre maio e junho &nbsp; Em meio \u00e0 crise or\u00e7ament\u00e1ria que&hellip;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1163,12],"tags":[],"class_list":["post-16763","post","type-post","status-publish","format-standard","hentry","category-clipping-cnpem","category-clipping-lnls","category-1163","category-12","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos - CNPEM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos - CNPEM\" \/>\n<meta property=\"og:description\" content=\"JCNot\u00edcias, 19\/05\/2017 &nbsp; MCTIC sinaliza que projeto \u00e9 prioridade nos investimentos do PAC e prev\u00ea liberar R$ 189 milh\u00f5es entre maio e junho &nbsp; Em meio \u00e0 crise or\u00e7ament\u00e1ria que&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/\" \/>\n<meta property=\"og:site_name\" content=\"CNPEM\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-26T18:51:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T18:45:00+00:00\" \/>\n<meta name=\"author\" content=\"Erik Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/\"},\"author\":{\"name\":\"Erik Medina\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"headline\":\"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos\",\"datePublished\":\"2017-05-26T18:51:52+00:00\",\"dateModified\":\"2022-01-21T18:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/\"},\"wordCount\":1303,\"articleSection\":[\"CNPEM na M\u00eddia\",\"LNLS na M\u00eddia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/\",\"url\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/\",\"name\":\"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos - CNPEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\"},\"datePublished\":\"2017-05-26T18:51:52+00:00\",\"dateModified\":\"2022-01-21T18:45:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnpem.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\",\"url\":\"https:\\\/\\\/cnpem.br\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"description\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"alternateName\":\"CNPEM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnpem.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\",\"name\":\"Erik Medina\",\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos - CNPEM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/","og_locale":"en_US","og_type":"article","og_title":"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos - CNPEM","og_description":"JCNot\u00edcias, 19\/05\/2017 &nbsp; MCTIC sinaliza que projeto \u00e9 prioridade nos investimentos do PAC e prev\u00ea liberar R$ 189 milh\u00f5es entre maio e junho &nbsp; Em meio \u00e0 crise or\u00e7ament\u00e1ria que&hellip;","og_url":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/","og_site_name":"CNPEM","article_published_time":"2017-05-26T18:51:52+00:00","article_modified_time":"2022-01-21T18:45:00+00:00","author":"Erik Medina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Erik Medina","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/#article","isPartOf":{"@id":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/"},"author":{"name":"Erik Medina","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"headline":"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos","datePublished":"2017-05-26T18:51:52+00:00","dateModified":"2022-01-21T18:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/"},"wordCount":1303,"articleSection":["CNPEM na M\u00eddia","LNLS na M\u00eddia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/","url":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/","name":"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos - CNPEM","isPartOf":{"@id":"https:\/\/cnpem.br\/#website"},"datePublished":"2017-05-26T18:51:52+00:00","dateModified":"2022-01-21T18:45:00+00:00","author":{"@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"breadcrumb":{"@id":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnpem.br\/em-ano-de-crise-construcao-do-laboratorio-sirius-aguarda-liberacao-imediata-de-recursos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnpem.br\/en\/"},{"@type":"ListItem","position":2,"name":"Em ano de crise, constru\u00e7\u00e3o do laborat\u00f3rio Sirius aguarda libera\u00e7\u00e3o imediata de recursos"}]},{"@type":"WebSite","@id":"https:\/\/cnpem.br\/#website","url":"https:\/\/cnpem.br\/","name":"Centro Nacional de Pesquisa em Energia e Materiais","description":"Centro Nacional de Pesquisa em Energia e Materiais","alternateName":"CNPEM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnpem.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef","name":"Erik Medina","url":""}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/per0Mi-4mn","_links":{"self":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/16763","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=16763"}],"version-history":[{"count":0,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/16763\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=16763"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=16763"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=16763"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}