{"id":11191,"date":"2015-01-21T13:22:43","date_gmt":"2015-01-21T13:22:43","guid":{"rendered":"https:\/\/www.cnpem.staging.wpengine.com\/?p=9602"},"modified":"2026-03-02T16:07:29","modified_gmt":"2026-03-02T19:07:29","slug":"lnnano-recebe-propostas-de-pesquisa","status":"publish","type":"post","link":"https:\/\/cnpem.br\/en\/lnnano-recebe-propostas-de-pesquisa\/","title":{"rendered":"LNNano recebe propostas de pesquisa"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>CRQ em 16\/01\/2015<\/em><strong><br \/>\n<\/strong><br \/>\nO Laborat\u00f3rio Nacional de Nanotecnologia (LNNano), que integra o Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), receber\u00e1 a partir do dia 20 de janeiro propostas de pesquisa que demandam a utiliza\u00e7\u00e3o de um microtom\u00f3grafo de raios X. A institui\u00e7\u00e3o disponibilizar\u00e1 aos aprovados o modelo SkyScan 1272.<\/p>\n<p style=\"text-align: justify;\">O equipamento permite a reconstru\u00e7\u00e3o tridimensional de diferentes amostras, de forma n\u00e3o destrutiva, com o intuito de revelar detalhes sobre forma e composi\u00e7\u00e3o das estruturas internas do material, em escala microm\u00e9trica. Utilizando a resolu\u00e7\u00e3o m\u00e1xima da c\u00e2mera, \u00e9 poss\u00edvel resolver estruturas com at\u00e9 350 nm de resolu\u00e7\u00e3o nominal.<\/p>\n<p style=\"text-align: justify;\">O microtom\u00f3grafo possui uma fonte de raios X de 20 keV a 100 keV. As dimens\u00f5es da amostra podem chegar a 75 mm de di\u00e2metro e 70 mm de comprimento. O equipamento realiza an\u00e1lises de amostras polim\u00e9ricas, geol\u00f3gicas, componentes e dispositivos eletr\u00f4nicos, materiais comp\u00f3sitos, produtos industriais, entre outros. Todas as propostas de pesquisa dever\u00e3o ser encaminhadas por meio do <strong><a href=\"https:\/\/portal2.cnpem.staging.wpengine.com\/cadastro\/login.jsf\" target=\"_blank\" rel=\"noopener\">Portal de Usu\u00e1rios do CNPEM<\/a><\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CRQ em 16\/01\/2015 O Laborat\u00f3rio Nacional de Nanotecnologia (LNNano), que integra o Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), receber\u00e1 a partir do dia 20 de janeiro propostas&hellip;<\/p>\n","protected":false},"author":17,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","_links_to":"","_links_to_target":""},"categories":[1163,44],"tags":[],"class_list":["post-11191","post","type-post","status-publish","format-standard","hentry","category-clipping-cnpem","category-clipping-lnnano","category-1163","category-44","description-off"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>LNNano recebe propostas de pesquisa - CNPEM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LNNano recebe propostas de pesquisa - CNPEM\" \/>\n<meta property=\"og:description\" content=\"CRQ em 16\/01\/2015 O Laborat\u00f3rio Nacional de Nanotecnologia (LNNano), que integra o Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), receber\u00e1 a partir do dia 20 de janeiro propostas&hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/\" \/>\n<meta property=\"og:site_name\" content=\"CNPEM\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-21T13:22:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-02T19:07:29+00:00\" \/>\n<meta name=\"author\" content=\"Erik Medina\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Erik Medina\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/\"},\"author\":{\"name\":\"Erik Medina\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"headline\":\"LNNano recebe propostas de pesquisa\",\"datePublished\":\"2015-01-21T13:22:43+00:00\",\"dateModified\":\"2026-03-02T19:07:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/\"},\"wordCount\":182,\"articleSection\":[\"CNPEM na M\u00eddia\",\"LNNano na M\u00eddia\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/\",\"url\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/\",\"name\":\"LNNano recebe propostas de pesquisa - CNPEM\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\"},\"datePublished\":\"2015-01-21T13:22:43+00:00\",\"dateModified\":\"2026-03-02T19:07:29+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/lnnano-recebe-propostas-de-pesquisa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/cnpem.br\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"LNNano recebe propostas de pesquisa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#website\",\"url\":\"https:\\\/\\\/cnpem.br\\\/\",\"name\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"description\":\"Centro Nacional de Pesquisa em Energia e Materiais\",\"alternateName\":\"CNPEM\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/cnpem.br\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/cnpem.br\\\/#\\\/schema\\\/person\\\/b957a8048be4b70d687484cae6b978ef\",\"name\":\"Erik Medina\",\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"LNNano recebe propostas de pesquisa - CNPEM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/","og_locale":"en_US","og_type":"article","og_title":"LNNano recebe propostas de pesquisa - CNPEM","og_description":"CRQ em 16\/01\/2015 O Laborat\u00f3rio Nacional de Nanotecnologia (LNNano), que integra o Centro Nacional de Pesquisa em Energia e Materiais (CNPEM), receber\u00e1 a partir do dia 20 de janeiro propostas&hellip;","og_url":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/","og_site_name":"CNPEM","article_published_time":"2015-01-21T13:22:43+00:00","article_modified_time":"2026-03-02T19:07:29+00:00","author":"Erik Medina","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Erik Medina","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/#article","isPartOf":{"@id":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/"},"author":{"name":"Erik Medina","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"headline":"LNNano recebe propostas de pesquisa","datePublished":"2015-01-21T13:22:43+00:00","dateModified":"2026-03-02T19:07:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/"},"wordCount":182,"articleSection":["CNPEM na M\u00eddia","LNNano na M\u00eddia"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/","url":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/","name":"LNNano recebe propostas de pesquisa - CNPEM","isPartOf":{"@id":"https:\/\/cnpem.br\/#website"},"datePublished":"2015-01-21T13:22:43+00:00","dateModified":"2026-03-02T19:07:29+00:00","author":{"@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef"},"breadcrumb":{"@id":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/cnpem.br\/lnnano-recebe-propostas-de-pesquisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/cnpem.br\/en\/"},{"@type":"ListItem","position":2,"name":"LNNano recebe propostas de pesquisa"}]},{"@type":"WebSite","@id":"https:\/\/cnpem.br\/#website","url":"https:\/\/cnpem.br\/","name":"Centro Nacional de Pesquisa em Energia e Materiais","description":"Centro Nacional de Pesquisa em Energia e Materiais","alternateName":"CNPEM","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cnpem.br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/cnpem.br\/#\/schema\/person\/b957a8048be4b70d687484cae6b978ef","name":"Erik Medina","url":""}]}},"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/per0Mi-2Uv","_links":{"self":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/11191","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/users\/17"}],"replies":[{"embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/comments?post=11191"}],"version-history":[{"count":0,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/posts\/11191\/revisions"}],"wp:attachment":[{"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/media?parent=11191"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/categories?post=11191"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cnpem.br\/en\/wp-json\/wp\/v2\/tags?post=11191"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}